{"id":67,"count":41,"description":"","link":"https:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/","name":"Sanaz Majd, MD","slug":"sanaz-majd-md","taxonomy":"category","parent":4,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sanaz Majd, MD Archives - Peyk Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanaz Majd, MD Archives - Peyk Magazine\" \/>\n<meta property=\"og:url\" content=\"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/\" \/>\n<meta property=\"og:site_name\" content=\"Peyk Magazine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/peykmagazine.com\\\/en\\\/category\\\/lifestyle\\\/sanaz-majd-md\\\/\",\"url\":\"http:\\\/\\\/peykmagazine.com\\\/en\\\/category\\\/lifestyle\\\/sanaz-majd-md\\\/\",\"name\":\"Sanaz Majd, MD Archives - Peyk Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/peykmagazine.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/peykmagazine.com\\\/en\\\/category\\\/lifestyle\\\/sanaz-majd-md\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/peykmagazine.com\\\/en\\\/category\\\/lifestyle\\\/sanaz-majd-md\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/peykmagazine.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lifestyle\",\"item\":\"http:\\\/\\\/peykmagazine.com\\\/en\\\/category\\\/lifestyle\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sanaz Majd, MD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/peykmagazine.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/peykmagazine.com\\\/en\\\/\",\"name\":\"Peyk Magazine\",\"description\":\"Persian Cultural Center\u2019s Bilingual Magazine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/peykmagazine.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sanaz Majd, MD Archives - Peyk Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/","og_locale":"en_US","og_type":"article","og_title":"Sanaz Majd, MD Archives - Peyk Magazine","og_url":"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/","og_site_name":"Peyk Magazine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/","url":"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/","name":"Sanaz Majd, MD Archives - Peyk Magazine","isPartOf":{"@id":"https:\/\/peykmagazine.com\/en\/#website"},"breadcrumb":{"@id":"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/sanaz-majd-md\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/peykmagazine.com\/en\/"},{"@type":"ListItem","position":2,"name":"Lifestyle","item":"http:\/\/peykmagazine.com\/en\/category\/lifestyle\/"},{"@type":"ListItem","position":3,"name":"Sanaz Majd, MD"}]},{"@type":"WebSite","@id":"https:\/\/peykmagazine.com\/en\/#website","url":"https:\/\/peykmagazine.com\/en\/","name":"Peyk Magazine","description":"Persian Cultural Center\u2019s Bilingual Magazine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/peykmagazine.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/peykmagazine.com\/en\/wp-json\/wp\/v2\/categories\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peykmagazine.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/peykmagazine.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/peykmagazine.com\/en\/wp-json\/wp\/v2\/categories\/4"}],"wp:post_type":[{"href":"https:\/\/peykmagazine.com\/en\/wp-json\/wp\/v2\/posts?categories=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}